{"id":2521,"date":"2024-08-20T14:44:05","date_gmt":"2024-08-20T12:44:05","guid":{"rendered":"https:\/\/www.belfor.com\/ch\/?p=2521"},"modified":"2024-08-20T14:46:43","modified_gmt":"2024-08-20T12:46:43","slug":"fact-sheet-localizzazione-di-perdite-e-deumidificazione","status":"publish","type":"post","link":"https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/","title":{"rendered":"Fact Sheet Localizzazione di perdite e deumidificazione"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.belfor.com\/ch\/wp-content\/uploads\/sites\/14\/2024\/06\/An-employee-using-a-device-to-find-a-leakage_1920x1080px-1024x576.jpg\" alt=\"Un employ\u00e9 qui utilise un appareil pour d\u00e9tecter une fuite\" class=\"wp-image-335\" srcset=\"https:\/\/www.belfor.com\/ch\/wp-content\/uploads\/sites\/14\/2024\/06\/An-employee-using-a-device-to-find-a-leakage_1920x1080px-1024x576.jpg 1024w, https:\/\/www.belfor.com\/ch\/wp-content\/uploads\/sites\/14\/2024\/06\/An-employee-using-a-device-to-find-a-leakage_1920x1080px-300x169.jpg 300w, https:\/\/www.belfor.com\/ch\/wp-content\/uploads\/sites\/14\/2024\/06\/An-employee-using-a-device-to-find-a-leakage_1920x1080px-768x432.jpg 768w, https:\/\/www.belfor.com\/ch\/wp-content\/uploads\/sites\/14\/2024\/06\/An-employee-using-a-device-to-find-a-leakage_1920x1080px-500x281.jpg 500w, https:\/\/www.belfor.com\/ch\/wp-content\/uploads\/sites\/14\/2024\/06\/An-employee-using-a-device-to-find-a-leakage_1920x1080px-200x113.jpg 200w, https:\/\/www.belfor.com\/ch\/wp-content\/uploads\/sites\/14\/2024\/06\/An-employee-using-a-device-to-find-a-leakage_1920x1080px.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div class=\"separators-custom-box  \"  >\n\n\t\n\t\n\t\t            <div class=\"cta_title\"\n\t\t\t\tstyle='color:#ffffff;'            >Fact Sheet Localizzazione di perdite e deumidificazione<\/div>\n\t\t\n\t\t            <a href=\"\/ch\/wp-content\/uploads\/sites\/14\/2024\/08\/Fact-Sheet-LOCALIZZAZIONE-DI-PERDITE-E-DEUMIDIFICAZIONE-CH-IT.pdf\"\n\t\t\t\t target=\"_blank\"               style=\"background-color:#dd3333;\"\n               class=\"c-btn -normal -inverted has-icon icon-right \"\n            >\n                <div class=\"label-up\"\n                style='color:#ffffff;'                >\n                    <span class=\"c-btn__txt\">Vista<\/span>\n\t\t\t\t\t\t<span class=\"c-btn__ico\"><svg width=\"30\" height=\"30\" class=\"icon icon-lib-icon-arrow4 \" aria-hidden=\"true\" role=\"img\"><use xlink:href=\"#lib-icon-arrow4\"><\/use><\/svg><\/span>\n                <\/div>\n                <div class=\"label-up\">\n                    <span class=\"c-btn__txt\">Vista<\/span>\n\t\t\t\t\t\t<span class=\"c-btn__ico\"><svg width=\"30\" height=\"30\" class=\"icon icon-lib-icon-arrow4 \" aria-hidden=\"true\" role=\"img\"><use xlink:href=\"#lib-icon-arrow4\"><\/use><\/svg><\/span>\n                <\/div>\n            <\/a>\n\t\t\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":336,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[34],"tags":[],"class_list":["post-2521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fact-sheets"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fact Sheet Localizzazione di perdite e deumidificazione - BELFOR Switzerland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fact Sheet Localizzazione di perdite e deumidificazione - BELFOR Switzerland\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/\" \/>\n<meta property=\"og:site_name\" content=\"BELFOR Switzerland\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-20T12:44:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-20T12:46:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.belfor.com\/ch\/wp-content\/uploads\/sites\/14\/2024\/06\/An-employee-using-a-device-to-find-a-leakage_1920x1080px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"janstruttmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"janstruttmann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/resources\\\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/resources\\\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\\\/\"},\"author\":{\"name\":\"janstruttmann\",\"@id\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/#\\\/schema\\\/person\\\/53356420af8a49df206f0987181714fd\"},\"headline\":\"Fact Sheet Localizzazione di perdite e deumidificazione\",\"datePublished\":\"2024-08-20T12:44:05+00:00\",\"dateModified\":\"2024-08-20T12:46:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/resources\\\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\\\/\"},\"wordCount\":7,\"image\":{\"@id\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/resources\\\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/06\\\/An-employee-using-a-device-to-find-a-leakage_1920x1080px.jpg\",\"articleSection\":[\"Fact Sheets\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/resources\\\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\\\/\",\"url\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/resources\\\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\\\/\",\"name\":\"Fact Sheet Localizzazione di perdite e deumidificazione - BELFOR Switzerland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/resources\\\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/resources\\\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/06\\\/An-employee-using-a-device-to-find-a-leakage_1920x1080px.jpg\",\"datePublished\":\"2024-08-20T12:44:05+00:00\",\"dateModified\":\"2024-08-20T12:46:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/#\\\/schema\\\/person\\\/53356420af8a49df206f0987181714fd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/resources\\\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/resources\\\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/resources\\\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/06\\\/An-employee-using-a-device-to-find-a-leakage_1920x1080px.jpg\",\"contentUrl\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/06\\\/An-employee-using-a-device-to-find-a-leakage_1920x1080px.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Un dipendente che utilizza un dispositivo per rilevare una perdita\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/resources\\\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fact Sheet Localizzazione di perdite e deumidificazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/\",\"name\":\"BELFOR Switzerland\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/#\\\/schema\\\/person\\\/53356420af8a49df206f0987181714fd\",\"name\":\"janstruttmann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ae6be3a060acc9e6dd1885d02ce9c98ca97ee31f9d8f20bedfca2ef03f3d10f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ae6be3a060acc9e6dd1885d02ce9c98ca97ee31f9d8f20bedfca2ef03f3d10f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4ae6be3a060acc9e6dd1885d02ce9c98ca97ee31f9d8f20bedfca2ef03f3d10f?s=96&d=mm&r=g\",\"caption\":\"janstruttmann\"},\"url\":\"https:\\\/\\\/www.belfor.com\\\/ch\\\/it\\\/resources\\\/author\\\/janstruttmann\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fact Sheet Localizzazione di perdite e deumidificazione - BELFOR Switzerland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/","og_locale":"it_IT","og_type":"article","og_title":"Fact Sheet Localizzazione di perdite e deumidificazione - BELFOR Switzerland","og_url":"https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/","og_site_name":"BELFOR Switzerland","article_published_time":"2024-08-20T12:44:05+00:00","article_modified_time":"2024-08-20T12:46:43+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.belfor.com\/ch\/wp-content\/uploads\/sites\/14\/2024\/06\/An-employee-using-a-device-to-find-a-leakage_1920x1080px.jpg","type":"image\/jpeg"}],"author":"janstruttmann","twitter_card":"summary_large_image","twitter_misc":{"Written by":"janstruttmann","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/#article","isPartOf":{"@id":"https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/"},"author":{"name":"janstruttmann","@id":"https:\/\/www.belfor.com\/ch\/it\/#\/schema\/person\/53356420af8a49df206f0987181714fd"},"headline":"Fact Sheet Localizzazione di perdite e deumidificazione","datePublished":"2024-08-20T12:44:05+00:00","dateModified":"2024-08-20T12:46:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/"},"wordCount":7,"image":{"@id":"https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.belfor.com\/ch\/wp-content\/uploads\/sites\/14\/2024\/06\/An-employee-using-a-device-to-find-a-leakage_1920x1080px.jpg","articleSection":["Fact Sheets"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/","url":"https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/","name":"Fact Sheet Localizzazione di perdite e deumidificazione - BELFOR Switzerland","isPartOf":{"@id":"https:\/\/www.belfor.com\/ch\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/#primaryimage"},"image":{"@id":"https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.belfor.com\/ch\/wp-content\/uploads\/sites\/14\/2024\/06\/An-employee-using-a-device-to-find-a-leakage_1920x1080px.jpg","datePublished":"2024-08-20T12:44:05+00:00","dateModified":"2024-08-20T12:46:43+00:00","author":{"@id":"https:\/\/www.belfor.com\/ch\/it\/#\/schema\/person\/53356420af8a49df206f0987181714fd"},"breadcrumb":{"@id":"https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/#primaryimage","url":"https:\/\/www.belfor.com\/ch\/wp-content\/uploads\/sites\/14\/2024\/06\/An-employee-using-a-device-to-find-a-leakage_1920x1080px.jpg","contentUrl":"https:\/\/www.belfor.com\/ch\/wp-content\/uploads\/sites\/14\/2024\/06\/An-employee-using-a-device-to-find-a-leakage_1920x1080px.jpg","width":1920,"height":1080,"caption":"Un dipendente che utilizza un dispositivo per rilevare una perdita"},{"@type":"BreadcrumbList","@id":"https:\/\/www.belfor.com\/ch\/it\/resources\/fact-sheet-localizzazione-di-perdite-e-deumidificazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.belfor.com\/ch\/it\/"},{"@type":"ListItem","position":2,"name":"Fact Sheet Localizzazione di perdite e deumidificazione"}]},{"@type":"WebSite","@id":"https:\/\/www.belfor.com\/ch\/it\/#website","url":"https:\/\/www.belfor.com\/ch\/it\/","name":"BELFOR Switzerland","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.belfor.com\/ch\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/www.belfor.com\/ch\/it\/#\/schema\/person\/53356420af8a49df206f0987181714fd","name":"janstruttmann","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/4ae6be3a060acc9e6dd1885d02ce9c98ca97ee31f9d8f20bedfca2ef03f3d10f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4ae6be3a060acc9e6dd1885d02ce9c98ca97ee31f9d8f20bedfca2ef03f3d10f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ae6be3a060acc9e6dd1885d02ce9c98ca97ee31f9d8f20bedfca2ef03f3d10f?s=96&d=mm&r=g","caption":"janstruttmann"},"url":"https:\/\/www.belfor.com\/ch\/it\/resources\/author\/janstruttmann\/"}]}},"_links":{"self":[{"href":"https:\/\/www.belfor.com\/ch\/it\/wp-json\/wp\/v2\/posts\/2521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.belfor.com\/ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.belfor.com\/ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.belfor.com\/ch\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.belfor.com\/ch\/it\/wp-json\/wp\/v2\/comments?post=2521"}],"version-history":[{"count":1,"href":"https:\/\/www.belfor.com\/ch\/it\/wp-json\/wp\/v2\/posts\/2521\/revisions"}],"predecessor-version":[{"id":2522,"href":"https:\/\/www.belfor.com\/ch\/it\/wp-json\/wp\/v2\/posts\/2521\/revisions\/2522"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.belfor.com\/ch\/it\/wp-json\/wp\/v2\/media\/336"}],"wp:attachment":[{"href":"https:\/\/www.belfor.com\/ch\/it\/wp-json\/wp\/v2\/media?parent=2521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.belfor.com\/ch\/it\/wp-json\/wp\/v2\/categories?post=2521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.belfor.com\/ch\/it\/wp-json\/wp\/v2\/tags?post=2521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}